{"id":15952,"date":"2020-12-29T02:28:03","date_gmt":"2021-04-08T06:37:14","guid":{"rendered":"https:\/\/diamant-strass-dmc.com\/perles-broderie\/dmc-diamonds-no-819-rose-layette\/"},"modified":"2023-05-24T23:40:46","modified_gmt":"2023-05-24T21:40:46","slug":"bag-diamonds-dmc-819","status":"publish","type":"product","link":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-819\/","title":{"rendered":"Diamantes DMC n\u00b0819 (Rose Layette)"},"content":{"rendered":"<p>Saco de 200 <strong>diamantes n\u00ba 819<\/strong> (c\u00f3digo DMC) <strong>Redondos ou quadrado.<\/strong><br \/>\nCor: <strong>Layette Rose<\/strong><br \/>\nFam\u00edlia cor: <strong>Rosa Violeta<\/strong><br \/>\nStrass acr\u00edlico de alta qualidade.<br \/>\n<strong>Tamanho standard<\/strong> (quadrados: 2,5 mm, Redondos: 2,8 mm).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saco de 200 diamantes n\u00ba 819 (c\u00f3digo DMC) Redondos ou quadrado. Cor: Layette Rose Fam\u00edlia cor: Rosa Violeta Strass acr\u00edlico de alta qualidade. Tamanho standard (quadrados: 2,5 mm, Redondos: 2,8 mm).<\/p>\n","protected":false},"featured_media":92225,"template":"","meta":{"footnotes":""},"product_brand":[],"product_cat":[1021],"class_list":["post-15952","product","type-product","status-publish","has-post-thumbnail","product_cat-rosa-pt-pt","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Saco de 200 diamantes n\u00ba 819 (c\u00f3digo DMC) Redondos ou quadrado. Cor: Layette Rose Fam\u00edlia cor: Rosa Violeta Strass acr\u00edlico de alta qualidade. Tamanho standard (quadrados: 2,5 mm, Redondos: 2,8 mm).\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-819\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_PT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\ud83d\udc8e Diamant Strass DMC - \ud83e\udd47 1\u00ba fornecedor de p\u00e9rolas diamond painting\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\ud83d\udc8e Diamantes DMC n\u00b0819 (Rose Layette) | Diamond Painting\" \/>\n\t\t<meta property=\"og:description\" content=\"Saco de 200 diamantes n\u00ba 819 (c\u00f3digo DMC) Redondos ou quadrado. Cor: Layette Rose Fam\u00edlia cor: Rosa Violeta Strass acr\u00edlico de alta qualidade. Tamanho standard (quadrados: 2,5 mm, Redondos: 2,8 mm).\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-819\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-04-08T06:37:14+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-05-24T21:40:46+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\ud83d\udc8e Diamantes DMC n\u00b0819 (Rose Layette) | Diamond Painting\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Saco de 200 diamantes n\u00ba 819 (c\u00f3digo DMC) Redondos ou quadrado. Cor: Layette Rose Fam\u00edlia cor: Rosa Violeta Strass acr\u00edlico de alta qualidade. Tamanho standard (quadrados: 2,5 mm, Redondos: 2,8 mm).\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-819\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/couleur\\\/rosa-pt-pt\\\/#listItem\",\"name\":\"\\ud83d\\udd34 Rosa\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/couleur\\\/rosa-pt-pt\\\/#listItem\",\"position\":2,\"name\":\"\\ud83d\\udd34 Rosa\",\"item\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/couleur\\\/rosa-pt-pt\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-819\\\/#listItem\",\"name\":\"Diamantes DMC n\\u00b0819 (Rose Layette)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/#listItem\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-819\\\/#listItem\",\"position\":3,\"name\":\"Diamantes DMC n\\u00b0819 (Rose Layette)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/couleur\\\/rosa-pt-pt\\\/#listItem\",\"name\":\"\\ud83d\\udd34 Rosa\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-819\\\/#itempage\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-819\\\/\",\"name\":\"\\ud83d\\udc8e Diamantes DMC n\\u00b0819 (Rose Layette) | Diamond Painting\",\"description\":\"Saco de 200 diamantes n\\u00ba 819 (c\\u00f3digo DMC) Redondos ou quadrado. Cor: Layette Rose Fam\\u00edlia cor: Rosa Violeta Strass acr\\u00edlico de alta qualidade. Tamanho standard (quadrados: 2,5 mm, Redondos: 2,8 mm).\",\"inLanguage\":\"pt-PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-819\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/wp-content\\\/uploads\\\/2022b\\\/02\\\/diamants-perles-dmc-819.jpg\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-819\\\/#mainImage\",\"width\":2236,\"height\":1688},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-819\\\/#mainImage\"},\"datePublished\":\"2020-12-29T02:28:03+01:00\",\"dateModified\":\"2023-05-24T23:40:46+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/#organization\",\"name\":\"Diamant Strass DMC\",\"description\":\"\\ud83e\\udd47 1\\u00ba fornecedor de p\\u00e9rolas diamond painting\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/\",\"telephone\":\"+33652550412\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cropped-Sans-titre-17.png\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-819\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-819\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/\",\"name\":\"\\ud83d\\udc8e Diamant Strass DMC\",\"description\":\"\\ud83e\\udd47 1\\u00ba fornecedor de p\\u00e9rolas diamond painting\",\"inLanguage\":\"pt-PT\",\"publisher\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\ud83d\udc8e Diamantes DMC n\u00b0819 (Rose Layette) | Diamond Painting","description":"Saco de 200 diamantes n\u00ba 819 (c\u00f3digo DMC) Redondos ou quadrado. Cor: Layette Rose Fam\u00edlia cor: Rosa Violeta Strass acr\u00edlico de alta qualidade. Tamanho standard (quadrados: 2,5 mm, Redondos: 2,8 mm).","canonical_url":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-819\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-819\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/#listItem","position":1,"name":"Accueil","item":"https:\/\/diamant-strass-dmc.com\/pt-pt\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/couleur\/rosa-pt-pt\/#listItem","name":"\ud83d\udd34 Rosa"}},{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/couleur\/rosa-pt-pt\/#listItem","position":2,"name":"\ud83d\udd34 Rosa","item":"https:\/\/diamant-strass-dmc.com\/pt-pt\/couleur\/rosa-pt-pt\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-819\/#listItem","name":"Diamantes DMC n\u00b0819 (Rose Layette)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/#listItem","name":"Accueil"}},{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-819\/#listItem","position":3,"name":"Diamantes DMC n\u00b0819 (Rose Layette)","previousItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/couleur\/rosa-pt-pt\/#listItem","name":"\ud83d\udd34 Rosa"}}]},{"@type":"ItemPage","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-819\/#itempage","url":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-819\/","name":"\ud83d\udc8e Diamantes DMC n\u00b0819 (Rose Layette) | Diamond Painting","description":"Saco de 200 diamantes n\u00ba 819 (c\u00f3digo DMC) Redondos ou quadrado. Cor: Layette Rose Fam\u00edlia cor: Rosa Violeta Strass acr\u00edlico de alta qualidade. Tamanho standard (quadrados: 2,5 mm, Redondos: 2,8 mm).","inLanguage":"pt-PT","isPartOf":{"@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/#website"},"breadcrumb":{"@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-819\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2022b\/02\/diamants-perles-dmc-819.jpg","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-819\/#mainImage","width":2236,"height":1688},"primaryImageOfPage":{"@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-819\/#mainImage"},"datePublished":"2020-12-29T02:28:03+01:00","dateModified":"2023-05-24T23:40:46+02:00"},{"@type":"Organization","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/#organization","name":"Diamant Strass DMC","description":"\ud83e\udd47 1\u00ba fornecedor de p\u00e9rolas diamond painting","url":"https:\/\/diamant-strass-dmc.com\/pt-pt\/","telephone":"+33652550412","logo":{"@type":"ImageObject","url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2022\/01\/cropped-Sans-titre-17.png","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-819\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-819\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/#website","url":"https:\/\/diamant-strass-dmc.com\/pt-pt\/","name":"\ud83d\udc8e Diamant Strass DMC","description":"\ud83e\udd47 1\u00ba fornecedor de p\u00e9rolas diamond painting","inLanguage":"pt-PT","publisher":{"@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/#organization"}}]},"og:locale":"pt_PT","og:site_name":"\ud83d\udc8e Diamant Strass DMC - \ud83e\udd47 1\u00ba fornecedor de p\u00e9rolas diamond painting","og:type":"article","og:title":"\ud83d\udc8e Diamantes DMC n\u00b0819 (Rose Layette) | Diamond Painting","og:description":"Saco de 200 diamantes n\u00ba 819 (c\u00f3digo DMC) Redondos ou quadrado. Cor: Layette Rose Fam\u00edlia cor: Rosa Violeta Strass acr\u00edlico de alta qualidade. Tamanho standard (quadrados: 2,5 mm, Redondos: 2,8 mm).","og:url":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-819\/","og:image":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp","og:image:secure_url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp","article:published_time":"2021-04-08T06:37:14+00:00","article:modified_time":"2023-05-24T21:40:46+00:00","twitter:card":"summary","twitter:title":"\ud83d\udc8e Diamantes DMC n\u00b0819 (Rose Layette) | Diamond Painting","twitter:description":"Saco de 200 diamantes n\u00ba 819 (c\u00f3digo DMC) Redondos ou quadrado. Cor: Layette Rose Fam\u00edlia cor: Rosa Violeta Strass acr\u00edlico de alta qualidade. Tamanho standard (quadrados: 2,5 mm, Redondos: 2,8 mm).","twitter:image":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp"},"aioseo_meta_data":{"post_id":"15952","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":"none","schema_type_options":"{\"webPage\":{\"webPageType\":\"WebPage\"},\"article\":{\"articleType\":\"BlogPosting\"},\"book\":[],\"course\":[],\"event\":[],\"jobPosting\":[],\"music\":[],\"person\":[],\"product\":[],\"recipe\":[],\"restaurant\":[],\"service\":[],\"software\":[],\"video\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"businessInfo":{"name":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"line1":"","line2":"","zip":"","city":"","state":"","country":""},"contact":{"email":"","phone":"","fax":""},"ids":{"vatID":"","taxID":"","chamberID":""},"payment":{"priceIndication":"","currenciesAccepted":"","methodsAccepted":""},"areaServed":""},"openingHours":{"show":false,"closedLabel":"","open24h":false,"open24hLabel":"","open247":false,"use24hFormat":false,"twoSets":false,"timezone":"","hours":[]}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-04-08 06:37:15","updated":"2025-06-05 06:51:55","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/diamant-strass-dmc.com\/pt-pt\/wp-json\/wp\/v2\/product\/15952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diamant-strass-dmc.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/diamant-strass-dmc.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/diamant-strass-dmc.com\/pt-pt\/wp-json\/wp\/v2\/product\/15952\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/pt-pt\/wp-json\/wp\/v2\/media\/92225"}],"wp:attachment":[{"href":"https:\/\/diamant-strass-dmc.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=15952"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=15952"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=15952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}