{"id":15329,"date":"2020-12-29T02:28:02","date_gmt":"2021-04-08T06:32:42","guid":{"rendered":"https:\/\/diamant-strass-dmc.com\/perles-broderie\/diamantes-dmc-no-796-azul-de-sevres\/"},"modified":"2021-04-08T08:32:42","modified_gmt":"2021-04-08T06:32:42","slug":"bag-diamonds-dmc-796","status":"publish","type":"product","link":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-796\/","title":{"rendered":"Diamantes DMC n\u00b0796 (Azul de S\u00e8vres)"},"content":{"rendered":"<p>Saco de 200 <strong>diamantes n\u00ba 796<\/strong> (c\u00f3digo DMC) <strong>Redondos ou quadrado.<\/strong><br \/>Cor: <strong>S\u00e8vres Blue<\/strong><br \/>Fam\u00edlia de cores: <strong>Azul<\/strong><br \/>Strass acr\u00edlico de alta qualidade.<br \/><strong>Tamanho standard<\/strong> (quadrados: 2,5 mm, Redondos: 2,8 mm).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saco de 200 diamantes n\u00ba 796 (c\u00f3digo DMC) Redondos ou quadrado.Cor: S\u00e8vres BlueFam\u00edlia de cores: AzulStrass acr\u00edlico de alta qualidade.Tamanho standard (quadrados: 2,5 mm, Redondos: 2,8 mm).<\/p>\n","protected":false},"featured_media":91460,"template":"","meta":{"footnotes":""},"product_brand":[],"product_cat":[599],"class_list":["post-15329","product","type-product","status-publish","has-post-thumbnail","product_cat-azul","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Saco de 200 diamantes n\u00ba 796 (c\u00f3digo DMC) Redondos ou quadrado.Cor: S\u00e8vres BlueFam\u00edlia de cores: AzulStrass acr\u00edlico de alta qualidade.Tamanho standard (quadrados: 2,5 mm, Redondos: 2,8 mm).\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-796\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_PT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\ud83d\udc8e Diamant Strass DMC - \ud83e\udd47 1\u00ba fornecedor de p\u00e9rolas diamond painting\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\ud83d\udc8e Diamantes DMC n\u00b0796 (Azul de S\u00e8vres) | Diamond Painting\" \/>\n\t\t<meta property=\"og:description\" content=\"Saco de 200 diamantes n\u00ba 796 (c\u00f3digo DMC) Redondos ou quadrado.Cor: S\u00e8vres BlueFam\u00edlia de cores: AzulStrass acr\u00edlico de alta qualidade.Tamanho standard (quadrados: 2,5 mm, Redondos: 2,8 mm).\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-796\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-04-08T06:32:42+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-04-08T06:32:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\ud83d\udc8e Diamantes DMC n\u00b0796 (Azul de S\u00e8vres) | Diamond Painting\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Saco de 200 diamantes n\u00ba 796 (c\u00f3digo DMC) Redondos ou quadrado.Cor: S\u00e8vres BlueFam\u00edlia de cores: AzulStrass acr\u00edlico de alta qualidade.Tamanho standard (quadrados: 2,5 mm, Redondos: 2,8 mm).\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-796\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/couleur\\\/azul\\\/#listItem\",\"name\":\"\\ud83d\\udd35 Azul\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/couleur\\\/azul\\\/#listItem\",\"position\":2,\"name\":\"\\ud83d\\udd35 Azul\",\"item\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/couleur\\\/azul\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-796\\\/#listItem\",\"name\":\"Diamantes DMC n\\u00b0796 (Azul de S\\u00e8vres)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/#listItem\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-796\\\/#listItem\",\"position\":3,\"name\":\"Diamantes DMC n\\u00b0796 (Azul de S\\u00e8vres)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/couleur\\\/azul\\\/#listItem\",\"name\":\"\\ud83d\\udd35 Azul\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-796\\\/#itempage\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-796\\\/\",\"name\":\"\\ud83d\\udc8e Diamantes DMC n\\u00b0796 (Azul de S\\u00e8vres) | Diamond Painting\",\"description\":\"Saco de 200 diamantes n\\u00ba 796 (c\\u00f3digo DMC) Redondos ou quadrado.Cor: S\\u00e8vres BlueFam\\u00edlia de cores: AzulStrass acr\\u00edlico de alta qualidade.Tamanho standard (quadrados: 2,5 mm, Redondos: 2,8 mm).\",\"inLanguage\":\"pt-PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-796\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/wp-content\\\/uploads\\\/2022b\\\/02\\\/diamants-perles-dmc-796.jpg\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-796\\\/#mainImage\",\"width\":2236,\"height\":1688},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-796\\\/#mainImage\"},\"datePublished\":\"2020-12-29T02:28:02+01:00\",\"dateModified\":\"2021-04-08T08:32:42+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/#organization\",\"name\":\"Diamant Strass DMC\",\"description\":\"\\ud83e\\udd47 1\\u00ba fornecedor de p\\u00e9rolas diamond painting\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/\",\"telephone\":\"+33652550412\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cropped-Sans-titre-17.png\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-796\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/perles-broderie\\\/bag-diamonds-dmc-796\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/\",\"name\":\"\\ud83d\\udc8e Diamant Strass DMC\",\"description\":\"\\ud83e\\udd47 1\\u00ba fornecedor de p\\u00e9rolas diamond painting\",\"inLanguage\":\"pt-PT\",\"publisher\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pt-pt\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\ud83d\udc8e Diamantes DMC n\u00b0796 (Azul de S\u00e8vres) | Diamond Painting","description":"Saco de 200 diamantes n\u00ba 796 (c\u00f3digo DMC) Redondos ou quadrado.Cor: S\u00e8vres BlueFam\u00edlia de cores: AzulStrass acr\u00edlico de alta qualidade.Tamanho standard (quadrados: 2,5 mm, Redondos: 2,8 mm).","canonical_url":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-796\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-796\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/#listItem","position":1,"name":"Accueil","item":"https:\/\/diamant-strass-dmc.com\/pt-pt\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/couleur\/azul\/#listItem","name":"\ud83d\udd35 Azul"}},{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/couleur\/azul\/#listItem","position":2,"name":"\ud83d\udd35 Azul","item":"https:\/\/diamant-strass-dmc.com\/pt-pt\/couleur\/azul\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-796\/#listItem","name":"Diamantes DMC n\u00b0796 (Azul de S\u00e8vres)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/#listItem","name":"Accueil"}},{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-796\/#listItem","position":3,"name":"Diamantes DMC n\u00b0796 (Azul de S\u00e8vres)","previousItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/couleur\/azul\/#listItem","name":"\ud83d\udd35 Azul"}}]},{"@type":"ItemPage","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-796\/#itempage","url":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-796\/","name":"\ud83d\udc8e Diamantes DMC n\u00b0796 (Azul de S\u00e8vres) | Diamond Painting","description":"Saco de 200 diamantes n\u00ba 796 (c\u00f3digo DMC) Redondos ou quadrado.Cor: S\u00e8vres BlueFam\u00edlia de cores: AzulStrass acr\u00edlico de alta qualidade.Tamanho standard (quadrados: 2,5 mm, Redondos: 2,8 mm).","inLanguage":"pt-PT","isPartOf":{"@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/#website"},"breadcrumb":{"@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-796\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2022b\/02\/diamants-perles-dmc-796.jpg","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-796\/#mainImage","width":2236,"height":1688},"primaryImageOfPage":{"@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-796\/#mainImage"},"datePublished":"2020-12-29T02:28:02+01:00","dateModified":"2021-04-08T08:32:42+02:00"},{"@type":"Organization","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/#organization","name":"Diamant Strass DMC","description":"\ud83e\udd47 1\u00ba fornecedor de p\u00e9rolas diamond painting","url":"https:\/\/diamant-strass-dmc.com\/pt-pt\/","telephone":"+33652550412","logo":{"@type":"ImageObject","url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2022\/01\/cropped-Sans-titre-17.png","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-796\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-796\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/#website","url":"https:\/\/diamant-strass-dmc.com\/pt-pt\/","name":"\ud83d\udc8e Diamant Strass DMC","description":"\ud83e\udd47 1\u00ba fornecedor de p\u00e9rolas diamond painting","inLanguage":"pt-PT","publisher":{"@id":"https:\/\/diamant-strass-dmc.com\/pt-pt\/#organization"}}]},"og:locale":"pt_PT","og:site_name":"\ud83d\udc8e Diamant Strass DMC - \ud83e\udd47 1\u00ba fornecedor de p\u00e9rolas diamond painting","og:type":"article","og:title":"\ud83d\udc8e Diamantes DMC n\u00b0796 (Azul de S\u00e8vres) | Diamond Painting","og:description":"Saco de 200 diamantes n\u00ba 796 (c\u00f3digo DMC) Redondos ou quadrado.Cor: S\u00e8vres BlueFam\u00edlia de cores: AzulStrass acr\u00edlico de alta qualidade.Tamanho standard (quadrados: 2,5 mm, Redondos: 2,8 mm).","og:url":"https:\/\/diamant-strass-dmc.com\/pt-pt\/perles-broderie\/bag-diamonds-dmc-796\/","og:image":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp","og:image:secure_url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp","article:published_time":"2021-04-08T06:32:42+00:00","article:modified_time":"2021-04-08T06:32:42+00:00","twitter:card":"summary","twitter:title":"\ud83d\udc8e Diamantes DMC n\u00b0796 (Azul de S\u00e8vres) | Diamond Painting","twitter:description":"Saco de 200 diamantes n\u00ba 796 (c\u00f3digo DMC) Redondos ou quadrado.Cor: S\u00e8vres BlueFam\u00edlia de cores: AzulStrass acr\u00edlico de alta qualidade.Tamanho standard (quadrados: 2,5 mm, Redondos: 2,8 mm).","twitter:image":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp"},"aioseo_meta_data":{"post_id":"15329","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-04-08 06:32:43","updated":"2025-06-05 06:30:56","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/diamant-strass-dmc.com\/pt-pt\/wp-json\/wp\/v2\/product\/15329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diamant-strass-dmc.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/diamant-strass-dmc.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/diamant-strass-dmc.com\/pt-pt\/wp-json\/wp\/v2\/product\/15329\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/pt-pt\/wp-json\/wp\/v2\/media\/91460"}],"wp:attachment":[{"href":"https:\/\/diamant-strass-dmc.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=15329"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=15329"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=15329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}