{"id":12613,"date":"2020-12-29T02:27:54","date_gmt":"2021-04-08T06:20:46","guid":{"rendered":"https:\/\/diamant-strass-dmc.com\/perles-broderie\/dmc-diamonds-no-606-bialy-czerwony\/"},"modified":"2023-05-25T00:50:41","modified_gmt":"2023-05-24T22:50:41","slug":"torba-diamenty-dmc-606","status":"publish","type":"product","link":"https:\/\/diamant-strass-dmc.com\/pl\/perles-broderie\/torba-diamenty-dmc-606\/","title":{"rendered":"Diamenty DMC nr 606 (Bia\u0142y Czerwony)"},"content":{"rendered":"<p>Worek z 200 <strong>diamentami nr 606<\/strong> (kod DMC) <strong>okr\u0105g\u0142y lub kwadratowy.<\/strong><br \/>\nKolor: <strong>Jasny czerwony<\/strong><br \/>\nRodzina kolor\u00f3w: <strong>Pomara\u0144czowy Br\u0105zowy<\/strong><br \/>\nWysokiej jako\u015bci akrylowe strass.<br \/>\n<strong>Standardowy rozmiar<\/strong> (kwadraty: 2,5 mm, okr\u0105g\u0142e: 2,8 mm).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Worek z 200 diamentami nr 606 (kod DMC) okr\u0105g\u0142y lub kwadratowy. Kolor: Jasny czerwony Rodzina kolor\u00f3w: Pomara\u0144czowy Br\u0105zowy Wysokiej jako\u015bci akrylowe strass. Standardowy rozmiar (kwadraty: 2,5 mm, okr\u0105g\u0142e: 2,8 mm).<\/p>\n","protected":false},"featured_media":90694,"template":"","meta":{"footnotes":""},"product_brand":[],"product_cat":[1358,838],"class_list":["post-12613","product","type-product","status-publish","has-post-thumbnail","product_cat-czerwony","product_cat-pomaranczowy","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Worek z 200 diamentami nr 606 (kod DMC) okr\u0105g\u0142y lub kwadratowy. Kolor: Jasny czerwony Rodzina kolor\u00f3w: Pomara\u0144czowy Br\u0105zowy Wysokiej jako\u015bci akrylowe strass. Standardowy rozmiar (kwadraty: 2,5 mm, okr\u0105g\u0142e: 2,8 mm).\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/diamant-strass-dmc.com\/pl\/perles-broderie\/torba-diamenty-dmc-606\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"pl_PL\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\ud83d\udc8e Diamant Strass DMC - \ud83e\udd47 Pierwszy dostawca pere\u0142 do diamond painting\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\ud83d\udc8e Diamenty DMC nr 606 (Bia\u0142y Czerwony) | Diamond Painting\" \/>\n\t\t<meta property=\"og:description\" content=\"Worek z 200 diamentami nr 606 (kod DMC) okr\u0105g\u0142y lub kwadratowy. Kolor: Jasny czerwony Rodzina kolor\u00f3w: Pomara\u0144czowy Br\u0105zowy Wysokiej jako\u015bci akrylowe strass. Standardowy rozmiar (kwadraty: 2,5 mm, okr\u0105g\u0142e: 2,8 mm).\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/diamant-strass-dmc.com\/pl\/perles-broderie\/torba-diamenty-dmc-606\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-04-08T06:20:46+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-05-24T22:50:41+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\ud83d\udc8e Diamenty DMC nr 606 (Bia\u0142y Czerwony) | Diamond Painting\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Worek z 200 diamentami nr 606 (kod DMC) okr\u0105g\u0142y lub kwadratowy. Kolor: Jasny czerwony Rodzina kolor\u00f3w: Pomara\u0144czowy Br\u0105zowy Wysokiej jako\u015bci akrylowe strass. Standardowy rozmiar (kwadraty: 2,5 mm, okr\u0105g\u0142e: 2,8 mm).\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/perles-broderie\\\/torba-diamenty-dmc-606\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/couleur\\\/pomaranczowy\\\/#listItem\",\"name\":\"\\ud83d\\udfe0 Pomara\\u0144czowy\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/couleur\\\/pomaranczowy\\\/#listItem\",\"position\":2,\"name\":\"\\ud83d\\udfe0 Pomara\\u0144czowy\",\"item\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/couleur\\\/pomaranczowy\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/perles-broderie\\\/torba-diamenty-dmc-606\\\/#listItem\",\"name\":\"Diamenty DMC nr 606 (Bia\\u0142y Czerwony)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/#listItem\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/perles-broderie\\\/torba-diamenty-dmc-606\\\/#listItem\",\"position\":3,\"name\":\"Diamenty DMC nr 606 (Bia\\u0142y Czerwony)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/couleur\\\/pomaranczowy\\\/#listItem\",\"name\":\"\\ud83d\\udfe0 Pomara\\u0144czowy\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/perles-broderie\\\/torba-diamenty-dmc-606\\\/#itempage\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/perles-broderie\\\/torba-diamenty-dmc-606\\\/\",\"name\":\"\\ud83d\\udc8e Diamenty DMC nr 606 (Bia\\u0142y Czerwony) | Diamond Painting\",\"description\":\"Worek z 200 diamentami nr 606 (kod DMC) okr\\u0105g\\u0142y lub kwadratowy. Kolor: Jasny czerwony Rodzina kolor\\u00f3w: Pomara\\u0144czowy Br\\u0105zowy Wysokiej jako\\u015bci akrylowe strass. Standardowy rozmiar (kwadraty: 2,5 mm, okr\\u0105g\\u0142e: 2,8 mm).\",\"inLanguage\":\"pl-PL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/perles-broderie\\\/torba-diamenty-dmc-606\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/wp-content\\\/uploads\\\/2022b\\\/02\\\/diamants-perles-dmc-606.jpg\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/perles-broderie\\\/torba-diamenty-dmc-606\\\/#mainImage\",\"width\":2236,\"height\":1688},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/perles-broderie\\\/torba-diamenty-dmc-606\\\/#mainImage\"},\"datePublished\":\"2020-12-29T02:27:54+01:00\",\"dateModified\":\"2023-05-25T00:50:41+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/#organization\",\"name\":\"Diamant Strass DMC\",\"description\":\"\\ud83e\\udd47 Pierwszy dostawca pere\\u0142 do diamond painting\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/\",\"telephone\":\"+33652550412\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cropped-Sans-titre-17.png\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/perles-broderie\\\/torba-diamenty-dmc-606\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/perles-broderie\\\/torba-diamenty-dmc-606\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/\",\"name\":\"\\ud83d\\udc8e Diamant Strass DMC\",\"description\":\"\\ud83e\\udd47 Pierwszy dostawca pere\\u0142 do diamond painting\",\"inLanguage\":\"pl-PL\",\"publisher\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/pl\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\ud83d\udc8e Diamenty DMC nr 606 (Bia\u0142y Czerwony) | Diamond Painting","description":"Worek z 200 diamentami nr 606 (kod DMC) okr\u0105g\u0142y lub kwadratowy. Kolor: Jasny czerwony Rodzina kolor\u00f3w: Pomara\u0144czowy Br\u0105zowy Wysokiej jako\u015bci akrylowe strass. Standardowy rozmiar (kwadraty: 2,5 mm, okr\u0105g\u0142e: 2,8 mm).","canonical_url":"https:\/\/diamant-strass-dmc.com\/pl\/perles-broderie\/torba-diamenty-dmc-606\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/diamant-strass-dmc.com\/pl\/perles-broderie\/torba-diamenty-dmc-606\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pl\/#listItem","position":1,"name":"Accueil","item":"https:\/\/diamant-strass-dmc.com\/pl\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pl\/couleur\/pomaranczowy\/#listItem","name":"\ud83d\udfe0 Pomara\u0144czowy"}},{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pl\/couleur\/pomaranczowy\/#listItem","position":2,"name":"\ud83d\udfe0 Pomara\u0144czowy","item":"https:\/\/diamant-strass-dmc.com\/pl\/couleur\/pomaranczowy\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pl\/perles-broderie\/torba-diamenty-dmc-606\/#listItem","name":"Diamenty DMC nr 606 (Bia\u0142y Czerwony)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pl\/#listItem","name":"Accueil"}},{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pl\/perles-broderie\/torba-diamenty-dmc-606\/#listItem","position":3,"name":"Diamenty DMC nr 606 (Bia\u0142y Czerwony)","previousItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/pl\/couleur\/pomaranczowy\/#listItem","name":"\ud83d\udfe0 Pomara\u0144czowy"}}]},{"@type":"ItemPage","@id":"https:\/\/diamant-strass-dmc.com\/pl\/perles-broderie\/torba-diamenty-dmc-606\/#itempage","url":"https:\/\/diamant-strass-dmc.com\/pl\/perles-broderie\/torba-diamenty-dmc-606\/","name":"\ud83d\udc8e Diamenty DMC nr 606 (Bia\u0142y Czerwony) | Diamond Painting","description":"Worek z 200 diamentami nr 606 (kod DMC) okr\u0105g\u0142y lub kwadratowy. Kolor: Jasny czerwony Rodzina kolor\u00f3w: Pomara\u0144czowy Br\u0105zowy Wysokiej jako\u015bci akrylowe strass. Standardowy rozmiar (kwadraty: 2,5 mm, okr\u0105g\u0142e: 2,8 mm).","inLanguage":"pl-PL","isPartOf":{"@id":"https:\/\/diamant-strass-dmc.com\/pl\/#website"},"breadcrumb":{"@id":"https:\/\/diamant-strass-dmc.com\/pl\/perles-broderie\/torba-diamenty-dmc-606\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2022b\/02\/diamants-perles-dmc-606.jpg","@id":"https:\/\/diamant-strass-dmc.com\/pl\/perles-broderie\/torba-diamenty-dmc-606\/#mainImage","width":2236,"height":1688},"primaryImageOfPage":{"@id":"https:\/\/diamant-strass-dmc.com\/pl\/perles-broderie\/torba-diamenty-dmc-606\/#mainImage"},"datePublished":"2020-12-29T02:27:54+01:00","dateModified":"2023-05-25T00:50:41+02:00"},{"@type":"Organization","@id":"https:\/\/diamant-strass-dmc.com\/pl\/#organization","name":"Diamant Strass DMC","description":"\ud83e\udd47 Pierwszy dostawca pere\u0142 do diamond painting","url":"https:\/\/diamant-strass-dmc.com\/pl\/","telephone":"+33652550412","logo":{"@type":"ImageObject","url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2022\/01\/cropped-Sans-titre-17.png","@id":"https:\/\/diamant-strass-dmc.com\/pl\/perles-broderie\/torba-diamenty-dmc-606\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/diamant-strass-dmc.com\/pl\/perles-broderie\/torba-diamenty-dmc-606\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/diamant-strass-dmc.com\/pl\/#website","url":"https:\/\/diamant-strass-dmc.com\/pl\/","name":"\ud83d\udc8e Diamant Strass DMC","description":"\ud83e\udd47 Pierwszy dostawca pere\u0142 do diamond painting","inLanguage":"pl-PL","publisher":{"@id":"https:\/\/diamant-strass-dmc.com\/pl\/#organization"}}]},"og:locale":"pl_PL","og:site_name":"\ud83d\udc8e Diamant Strass DMC - \ud83e\udd47 Pierwszy dostawca pere\u0142 do diamond painting","og:type":"article","og:title":"\ud83d\udc8e Diamenty DMC nr 606 (Bia\u0142y Czerwony) | Diamond Painting","og:description":"Worek z 200 diamentami nr 606 (kod DMC) okr\u0105g\u0142y lub kwadratowy. Kolor: Jasny czerwony Rodzina kolor\u00f3w: Pomara\u0144czowy Br\u0105zowy Wysokiej jako\u015bci akrylowe strass. Standardowy rozmiar (kwadraty: 2,5 mm, okr\u0105g\u0142e: 2,8 mm).","og:url":"https:\/\/diamant-strass-dmc.com\/pl\/perles-broderie\/torba-diamenty-dmc-606\/","og:image":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp","og:image:secure_url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp","article:published_time":"2021-04-08T06:20:46+00:00","article:modified_time":"2023-05-24T22:50:41+00:00","twitter:card":"summary","twitter:title":"\ud83d\udc8e Diamenty DMC nr 606 (Bia\u0142y Czerwony) | Diamond Painting","twitter:description":"Worek z 200 diamentami nr 606 (kod DMC) okr\u0105g\u0142y lub kwadratowy. Kolor: Jasny czerwony Rodzina kolor\u00f3w: Pomara\u0144czowy Br\u0105zowy Wysokiej jako\u015bci akrylowe strass. Standardowy rozmiar (kwadraty: 2,5 mm, okr\u0105g\u0142e: 2,8 mm).","twitter:image":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp"},"aioseo_meta_data":{"post_id":"12613","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":"none","schema_type_options":"{\"webPage\":{\"webPageType\":\"WebPage\"},\"article\":{\"articleType\":\"BlogPosting\"},\"book\":[],\"course\":[],\"event\":[],\"jobPosting\":[],\"music\":[],\"person\":[],\"product\":[],\"recipe\":[],\"restaurant\":[],\"service\":[],\"software\":[],\"video\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"businessInfo":{"name":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"line1":"","line2":"","zip":"","city":"","state":"","country":""},"contact":{"email":"","phone":"","fax":""},"ids":{"vatID":"","taxID":"","chamberID":""},"payment":{"priceIndication":"","currenciesAccepted":"","methodsAccepted":""},"areaServed":""},"openingHours":{"show":false,"closedLabel":"","open24h":false,"open24hLabel":"","open247":false,"use24hFormat":false,"twoSets":false,"timezone":"","hours":[]}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-04-08 06:20:47","updated":"2025-06-05 04:55:54","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/diamant-strass-dmc.com\/pl\/wp-json\/wp\/v2\/product\/12613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diamant-strass-dmc.com\/pl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/diamant-strass-dmc.com\/pl\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/diamant-strass-dmc.com\/pl\/wp-json\/wp\/v2\/product\/12613\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/pl\/wp-json\/wp\/v2\/media\/90694"}],"wp:attachment":[{"href":"https:\/\/diamant-strass-dmc.com\/pl\/wp-json\/wp\/v2\/media?parent=12613"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/pl\/wp-json\/wp\/v2\/product_brand?post=12613"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/pl\/wp-json\/wp\/v2\/product_cat?post=12613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}