{"id":9811,"date":"2020-12-29T02:27:43","date_gmt":"2021-04-08T05:55:41","guid":{"rendered":"https:\/\/diamant-strass-dmc.com\/perles-broderie\/dmc-diamonds-no-326-robijnrood\/"},"modified":"2021-04-08T07:55:41","modified_gmt":"2021-04-08T05:55:41","slug":"zak-diamanten-dmc-326","status":"publish","type":"product","link":"https:\/\/diamant-strass-dmc.com\/nl\/perles-broderie\/zak-diamanten-dmc-326\/","title":{"rendered":"Drills DMC n\u00b0326 (Robijnrood)"},"content":{"rendered":"<p>Zak van 200 <strong>steentjes nr. 326<\/strong> (DMC-code) <strong>rond of vierkant.<\/strong><br \/>\nKleur: <strong>Robijnrood<\/strong><br \/>\nKleur familie: <strong>Rose violet<\/strong><br \/>\nHoge kwaliteit acryl strass.<br \/>\n<strong>Standaardmaat<\/strong> (vierkanten: 2,5 mm, rond: 2,8 mm).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zak van 200 steentjes nr. 326 (DMC-code) rond of vierkant. Kleur: Robijnrood Kleur familie: Rose violet Hoge kwaliteit acryl strass. Standaardmaat (vierkanten: 2,5 mm, rond: 2,8 mm).<\/p>\n","protected":false},"featured_media":96103,"template":"","meta":{"footnotes":""},"product_brand":[],"product_cat":[1333],"class_list":["post-9811","product","type-product","status-publish","has-post-thumbnail","product_cat-rood","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Zak van 200 steentjes nr. 326 (DMC-code) rond of vierkant. Kleur: Robijnrood Kleur familie: Rose violet Hoge kwaliteit acryl strass. Standaardmaat (vierkanten: 2,5 mm, rond: 2,8 mm).\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/diamant-strass-dmc.com\/nl\/perles-broderie\/zak-diamanten-dmc-326\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"nl_NL\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\ud83d\udc8e Diamant Strass DMC - \ud83e\udd47 1e leverancier van diamond painting kralen\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\ud83d\udc8e Drills DMC n\u00b0326 (Robijnrood) | Diamond Painting\" \/>\n\t\t<meta property=\"og:description\" content=\"Zak van 200 steentjes nr. 326 (DMC-code) rond of vierkant. Kleur: Robijnrood Kleur familie: Rose violet Hoge kwaliteit acryl strass. Standaardmaat (vierkanten: 2,5 mm, rond: 2,8 mm).\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/diamant-strass-dmc.com\/nl\/perles-broderie\/zak-diamanten-dmc-326\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-04-08T05:55:41+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-04-08T05:55:41+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\ud83d\udc8e Drills DMC n\u00b0326 (Robijnrood) | Diamond Painting\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Zak van 200 steentjes nr. 326 (DMC-code) rond of vierkant. Kleur: Robijnrood Kleur familie: Rose violet Hoge kwaliteit acryl strass. Standaardmaat (vierkanten: 2,5 mm, rond: 2,8 mm).\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/perles-broderie\\\/zak-diamanten-dmc-326\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/couleur\\\/rood\\\/#listItem\",\"name\":\"\\ud83d\\udd34 Rood\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/couleur\\\/rood\\\/#listItem\",\"position\":2,\"name\":\"\\ud83d\\udd34 Rood\",\"item\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/couleur\\\/rood\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/perles-broderie\\\/zak-diamanten-dmc-326\\\/#listItem\",\"name\":\"Drills DMC n\\u00b0326 (Robijnrood)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/#listItem\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/perles-broderie\\\/zak-diamanten-dmc-326\\\/#listItem\",\"position\":3,\"name\":\"Drills DMC n\\u00b0326 (Robijnrood)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/couleur\\\/rood\\\/#listItem\",\"name\":\"\\ud83d\\udd34 Rood\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/perles-broderie\\\/zak-diamanten-dmc-326\\\/#itempage\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/perles-broderie\\\/zak-diamanten-dmc-326\\\/\",\"name\":\"\\ud83d\\udc8e Drills DMC n\\u00b0326 (Robijnrood) | Diamond Painting\",\"description\":\"Zak van 200 steentjes nr. 326 (DMC-code) rond of vierkant. Kleur: Robijnrood Kleur familie: Rose violet Hoge kwaliteit acryl strass. Standaardmaat (vierkanten: 2,5 mm, rond: 2,8 mm).\",\"inLanguage\":\"nl-NL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/perles-broderie\\\/zak-diamanten-dmc-326\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/wp-content\\\/uploads\\\/2022b\\\/02\\\/diamants-perles-dmc-326.jpg\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/perles-broderie\\\/zak-diamanten-dmc-326\\\/#mainImage\",\"width\":2236,\"height\":1688},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/perles-broderie\\\/zak-diamanten-dmc-326\\\/#mainImage\"},\"datePublished\":\"2020-12-29T02:27:43+01:00\",\"dateModified\":\"2021-04-08T07:55:41+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/#organization\",\"name\":\"Diamant Strass DMC\",\"description\":\"\\ud83e\\udd47 1e leverancier van diamond painting kralen\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/\",\"telephone\":\"+33652550412\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cropped-Sans-titre-17.png\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/perles-broderie\\\/zak-diamanten-dmc-326\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/perles-broderie\\\/zak-diamanten-dmc-326\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/\",\"name\":\"\\ud83d\\udc8e Diamant Strass DMC\",\"description\":\"\\ud83e\\udd47 1e leverancier van diamond painting kralen\",\"inLanguage\":\"nl-NL\",\"publisher\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/nl\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\ud83d\udc8e Drills DMC n\u00b0326 (Robijnrood) | Diamond Painting","description":"Zak van 200 steentjes nr. 326 (DMC-code) rond of vierkant. Kleur: Robijnrood Kleur familie: Rose violet Hoge kwaliteit acryl strass. Standaardmaat (vierkanten: 2,5 mm, rond: 2,8 mm).","canonical_url":"https:\/\/diamant-strass-dmc.com\/nl\/perles-broderie\/zak-diamanten-dmc-326\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/diamant-strass-dmc.com\/nl\/perles-broderie\/zak-diamanten-dmc-326\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/nl\/#listItem","position":1,"name":"Accueil","item":"https:\/\/diamant-strass-dmc.com\/nl\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/nl\/couleur\/rood\/#listItem","name":"\ud83d\udd34 Rood"}},{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/nl\/couleur\/rood\/#listItem","position":2,"name":"\ud83d\udd34 Rood","item":"https:\/\/diamant-strass-dmc.com\/nl\/couleur\/rood\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/nl\/perles-broderie\/zak-diamanten-dmc-326\/#listItem","name":"Drills DMC n\u00b0326 (Robijnrood)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/nl\/#listItem","name":"Accueil"}},{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/nl\/perles-broderie\/zak-diamanten-dmc-326\/#listItem","position":3,"name":"Drills DMC n\u00b0326 (Robijnrood)","previousItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/nl\/couleur\/rood\/#listItem","name":"\ud83d\udd34 Rood"}}]},{"@type":"ItemPage","@id":"https:\/\/diamant-strass-dmc.com\/nl\/perles-broderie\/zak-diamanten-dmc-326\/#itempage","url":"https:\/\/diamant-strass-dmc.com\/nl\/perles-broderie\/zak-diamanten-dmc-326\/","name":"\ud83d\udc8e Drills DMC n\u00b0326 (Robijnrood) | Diamond Painting","description":"Zak van 200 steentjes nr. 326 (DMC-code) rond of vierkant. Kleur: Robijnrood Kleur familie: Rose violet Hoge kwaliteit acryl strass. Standaardmaat (vierkanten: 2,5 mm, rond: 2,8 mm).","inLanguage":"nl-NL","isPartOf":{"@id":"https:\/\/diamant-strass-dmc.com\/nl\/#website"},"breadcrumb":{"@id":"https:\/\/diamant-strass-dmc.com\/nl\/perles-broderie\/zak-diamanten-dmc-326\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2022b\/02\/diamants-perles-dmc-326.jpg","@id":"https:\/\/diamant-strass-dmc.com\/nl\/perles-broderie\/zak-diamanten-dmc-326\/#mainImage","width":2236,"height":1688},"primaryImageOfPage":{"@id":"https:\/\/diamant-strass-dmc.com\/nl\/perles-broderie\/zak-diamanten-dmc-326\/#mainImage"},"datePublished":"2020-12-29T02:27:43+01:00","dateModified":"2021-04-08T07:55:41+02:00"},{"@type":"Organization","@id":"https:\/\/diamant-strass-dmc.com\/nl\/#organization","name":"Diamant Strass DMC","description":"\ud83e\udd47 1e leverancier van diamond painting kralen","url":"https:\/\/diamant-strass-dmc.com\/nl\/","telephone":"+33652550412","logo":{"@type":"ImageObject","url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2022\/01\/cropped-Sans-titre-17.png","@id":"https:\/\/diamant-strass-dmc.com\/nl\/perles-broderie\/zak-diamanten-dmc-326\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/diamant-strass-dmc.com\/nl\/perles-broderie\/zak-diamanten-dmc-326\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/diamant-strass-dmc.com\/nl\/#website","url":"https:\/\/diamant-strass-dmc.com\/nl\/","name":"\ud83d\udc8e Diamant Strass DMC","description":"\ud83e\udd47 1e leverancier van diamond painting kralen","inLanguage":"nl-NL","publisher":{"@id":"https:\/\/diamant-strass-dmc.com\/nl\/#organization"}}]},"og:locale":"nl_NL","og:site_name":"\ud83d\udc8e Diamant Strass DMC - \ud83e\udd47 1e leverancier van diamond painting kralen","og:type":"article","og:title":"\ud83d\udc8e Drills DMC n\u00b0326 (Robijnrood) | Diamond Painting","og:description":"Zak van 200 steentjes nr. 326 (DMC-code) rond of vierkant. Kleur: Robijnrood Kleur familie: Rose violet Hoge kwaliteit acryl strass. Standaardmaat (vierkanten: 2,5 mm, rond: 2,8 mm).","og:url":"https:\/\/diamant-strass-dmc.com\/nl\/perles-broderie\/zak-diamanten-dmc-326\/","og:image":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp","og:image:secure_url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp","article:published_time":"2021-04-08T05:55:41+00:00","article:modified_time":"2021-04-08T05:55:41+00:00","twitter:card":"summary","twitter:title":"\ud83d\udc8e Drills DMC n\u00b0326 (Robijnrood) | Diamond Painting","twitter:description":"Zak van 200 steentjes nr. 326 (DMC-code) rond of vierkant. Kleur: Robijnrood Kleur familie: Rose violet Hoge kwaliteit acryl strass. Standaardmaat (vierkanten: 2,5 mm, rond: 2,8 mm).","twitter:image":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp"},"aioseo_meta_data":{"post_id":"9811","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":"none","schema_type_options":"{\"webPage\":{\"webPageType\":\"WebPage\"},\"article\":{\"articleType\":\"BlogPosting\"},\"book\":[],\"course\":[],\"event\":[],\"jobPosting\":[],\"music\":[],\"person\":[],\"product\":[],\"recipe\":[],\"restaurant\":[],\"service\":[],\"software\":[],\"video\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"businessInfo":{"name":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"line1":"","line2":"","zip":"","city":"","state":"","country":""},"contact":{"email":"","phone":"","fax":""},"ids":{"vatID":"","taxID":"","chamberID":""},"payment":{"priceIndication":"","currenciesAccepted":"","methodsAccepted":""},"areaServed":""},"openingHours":{"show":false,"closedLabel":"","open24h":false,"open24hLabel":"","open247":false,"use24hFormat":false,"twoSets":false,"timezone":"","hours":[]}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-04-08 05:55:42","updated":"2025-06-05 02:57:54","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/diamant-strass-dmc.com\/nl\/wp-json\/wp\/v2\/product\/9811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diamant-strass-dmc.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/diamant-strass-dmc.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/diamant-strass-dmc.com\/nl\/wp-json\/wp\/v2\/product\/9811\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/nl\/wp-json\/wp\/v2\/media\/96103"}],"wp:attachment":[{"href":"https:\/\/diamant-strass-dmc.com\/nl\/wp-json\/wp\/v2\/media?parent=9811"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/nl\/wp-json\/wp\/v2\/product_brand?post=9811"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/nl\/wp-json\/wp\/v2\/product_cat?post=9811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}