{"id":46311,"date":"2022-09-06T20:04:44","date_gmt":"2022-09-06T18:04:44","guid":{"rendered":"https:\/\/diamant-strass-dmc.com\/perles-broderie\/espatula-correctiva-para-bordado-de-diamantes\/"},"modified":"2023-12-03T18:13:05","modified_gmt":"2023-12-03T17:13:05","slug":"espatula-correctora-para-bordado-diamante","status":"publish","type":"product","link":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/espatula-correctora-para-bordado-diamante\/","title":{"rendered":"Esp\u00e1tula correctora para bordado de diamantes"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Al introducirla <strong>entre cada fila de diamantes<\/strong>, esta esp\u00e1tula permite <strong>alinearlos perfectamente<\/strong>.<\/p>\n<p>Altura: 14 cm<br \/>\nAnchura: 10 cm<\/p>\n","protected":false},"featured_media":44495,"template":"","meta":{"footnotes":""},"product_brand":[],"product_cat":[7182],"class_list":["post-46311","product","type-product","status-publish","has-post-thumbnail","product_cat-accesorios","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Al introducirla entre cada fila de diamantes, esta esp\u00e1tula permite alinearlos perfectamente. Altura: 14 cm Anchura: 10 cm\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/espatula-correctora-para-bordado-diamante\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\ud83d\udc8e Diamant Strass DMC - \ud83e\udd47 1er proveedor de cuentas diamond painting\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\ud83d\udc8e Esp\u00e1tula correctora para bordado de diamantes | Diamond Painting\" \/>\n\t\t<meta property=\"og:description\" content=\"Al introducirla entre cada fila de diamantes, esta esp\u00e1tula permite alinearlos perfectamente. Altura: 14 cm Anchura: 10 cm\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/espatula-correctora-para-bordado-diamante\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-09-06T18:04:44+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-12-03T17:13:05+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\ud83d\udc8e Esp\u00e1tula correctora para bordado de diamantes | Diamond Painting\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Al introducirla entre cada fila de diamantes, esta esp\u00e1tula permite alinearlos perfectamente. Altura: 14 cm Anchura: 10 cm\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/espatula-correctora-para-bordado-diamante\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/couleur\\\/accesorios\\\/#listItem\",\"name\":\"Accesorios\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/couleur\\\/accesorios\\\/#listItem\",\"position\":2,\"name\":\"Accesorios\",\"item\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/couleur\\\/accesorios\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/espatula-correctora-para-bordado-diamante\\\/#listItem\",\"name\":\"Esp\\u00e1tula correctora para bordado de diamantes\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#listItem\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/espatula-correctora-para-bordado-diamante\\\/#listItem\",\"position\":3,\"name\":\"Esp\\u00e1tula correctora para bordado de diamantes\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/couleur\\\/accesorios\\\/#listItem\",\"name\":\"Accesorios\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/espatula-correctora-para-bordado-diamante\\\/#itempage\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/espatula-correctora-para-bordado-diamante\\\/\",\"name\":\"\\ud83d\\udc8e Esp\\u00e1tula correctora para bordado de diamantes | Diamond Painting\",\"description\":\"Al introducirla entre cada fila de diamantes, esta esp\\u00e1tula permite alinearlos perfectamente. Altura: 14 cm Anchura: 10 cm\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/espatula-correctora-para-bordado-diamante\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/spatule-correctrice-diamond-painting-broderie-diamant.jpg\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/espatula-correctora-para-bordado-diamante\\\/#mainImage\",\"width\":607,\"height\":607,\"caption\":\"Esp\\u00e1tula correctora, corrector para pintura diamantada\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/espatula-correctora-para-bordado-diamante\\\/#mainImage\"},\"datePublished\":\"2022-09-06T20:04:44+02:00\",\"dateModified\":\"2023-12-03T18:13:05+01:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#organization\",\"name\":\"Diamant Strass DMC\",\"description\":\"\\ud83e\\udd47 1er proveedor de cuentas diamond painting\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/\",\"telephone\":\"+33652550412\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cropped-Sans-titre-17.png\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/espatula-correctora-para-bordado-diamante\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/espatula-correctora-para-bordado-diamante\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/\",\"name\":\"\\ud83d\\udc8e Diamant Strass DMC\",\"description\":\"\\ud83e\\udd47 1er proveedor de cuentas diamond painting\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\ud83d\udc8e Esp\u00e1tula correctora para bordado de diamantes | Diamond Painting","description":"Al introducirla entre cada fila de diamantes, esta esp\u00e1tula permite alinearlos perfectamente. Altura: 14 cm Anchura: 10 cm","canonical_url":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/espatula-correctora-para-bordado-diamante\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/espatula-correctora-para-bordado-diamante\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/#listItem","position":1,"name":"Accueil","item":"https:\/\/diamant-strass-dmc.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/couleur\/accesorios\/#listItem","name":"Accesorios"}},{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/couleur\/accesorios\/#listItem","position":2,"name":"Accesorios","item":"https:\/\/diamant-strass-dmc.com\/es\/couleur\/accesorios\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/espatula-correctora-para-bordado-diamante\/#listItem","name":"Esp\u00e1tula correctora para bordado de diamantes"},"previousItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/#listItem","name":"Accueil"}},{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/espatula-correctora-para-bordado-diamante\/#listItem","position":3,"name":"Esp\u00e1tula correctora para bordado de diamantes","previousItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/couleur\/accesorios\/#listItem","name":"Accesorios"}}]},{"@type":"ItemPage","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/espatula-correctora-para-bordado-diamante\/#itempage","url":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/espatula-correctora-para-bordado-diamante\/","name":"\ud83d\udc8e Esp\u00e1tula correctora para bordado de diamantes | Diamond Painting","description":"Al introducirla entre cada fila de diamantes, esta esp\u00e1tula permite alinearlos perfectamente. Altura: 14 cm Anchura: 10 cm","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/espatula-correctora-para-bordado-diamante\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2022\/09\/spatule-correctrice-diamond-painting-broderie-diamant.jpg","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/espatula-correctora-para-bordado-diamante\/#mainImage","width":607,"height":607,"caption":"Esp\u00e1tula correctora, corrector para pintura diamantada"},"primaryImageOfPage":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/espatula-correctora-para-bordado-diamante\/#mainImage"},"datePublished":"2022-09-06T20:04:44+02:00","dateModified":"2023-12-03T18:13:05+01:00"},{"@type":"Organization","@id":"https:\/\/diamant-strass-dmc.com\/es\/#organization","name":"Diamant Strass DMC","description":"\ud83e\udd47 1er proveedor de cuentas diamond painting","url":"https:\/\/diamant-strass-dmc.com\/es\/","telephone":"+33652550412","logo":{"@type":"ImageObject","url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2022\/01\/cropped-Sans-titre-17.png","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/espatula-correctora-para-bordado-diamante\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/espatula-correctora-para-bordado-diamante\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/diamant-strass-dmc.com\/es\/#website","url":"https:\/\/diamant-strass-dmc.com\/es\/","name":"\ud83d\udc8e Diamant Strass DMC","description":"\ud83e\udd47 1er proveedor de cuentas diamond painting","inLanguage":"es-ES","publisher":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"\ud83d\udc8e Diamant Strass DMC - \ud83e\udd47 1er proveedor de cuentas diamond painting","og:type":"article","og:title":"\ud83d\udc8e Esp\u00e1tula correctora para bordado de diamantes | Diamond Painting","og:description":"Al introducirla entre cada fila de diamantes, esta esp\u00e1tula permite alinearlos perfectamente. Altura: 14 cm Anchura: 10 cm","og:url":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/espatula-correctora-para-bordado-diamante\/","og:image":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp","og:image:secure_url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp","article:published_time":"2022-09-06T18:04:44+00:00","article:modified_time":"2023-12-03T17:13:05+00:00","twitter:card":"summary","twitter:title":"\ud83d\udc8e Esp\u00e1tula correctora para bordado de diamantes | Diamond Painting","twitter:description":"Al introducirla entre cada fila de diamantes, esta esp\u00e1tula permite alinearlos perfectamente. Altura: 14 cm Anchura: 10 cm","twitter:image":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp"},"aioseo_meta_data":{"post_id":"46311","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[],"defaultGraph":"WebPage","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"},\"blockGraphs\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-10-05 00:01:42","updated":"2026-03-10 01:01:28","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product\/46311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product\/46311\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/media\/44495"}],"wp:attachment":[{"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/media?parent=46311"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product_brand?post=46311"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product_cat?post=46311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}