{"id":20957,"date":"2020-12-29T02:28:18","date_gmt":"2021-04-08T06:52:36","guid":{"rendered":"https:\/\/diamant-strass-dmc.com\/perles-broderie\/diamantes-dmc-no-3340-albaricoque\/"},"modified":"2021-04-08T08:52:36","modified_gmt":"2021-04-08T06:52:36","slug":"bolsa-diamantes-dmc-3340","status":"publish","type":"product","link":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3340\/","title":{"rendered":"Diamantes DMC n\u00b03340 (Albaricoque)"},"content":{"rendered":"<p>Bolsa de 200 <strong>diamantes n\u00b03340<\/strong> (c\u00f3digo DMC) <strong>Redondos o Cuadrados.<\/strong><br \/>\n<br \/>\ud83c\udfa8 Color: <strong>Albaricoque<\/strong><br \/>\n\ud83c\udf08 Familia de colores: <strong>Marr\u00f3n anaranjado<\/strong><br \/>\n\u2b50 <strong>Calidad superior<\/strong> aprobada por nuestros clientes<br \/>\n\u2705 <strong>Tama\u00f1o est\u00e1ndar<\/strong> (cuadrados: 2,5 mm, redondos: 2,8 mm)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bolsa de 200 diamantes n\u00b03340 (c\u00f3digo DMC) Redondos o Cuadrados. \ud83c\udfa8 Color: Albaricoque \ud83c\udf08 Familia de colores: Marr\u00f3n anaranjado \u2b50 Calidad superior aprobada por nuestros clientes \u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)<\/p>\n","protected":false},"featured_media":90457,"template":"","meta":{"footnotes":""},"product_brand":[],"product_cat":[841,1012],"class_list":["post-20957","product","type-product","status-publish","has-post-thumbnail","product_cat-naranja","product_cat-rosa-es","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Bolsa de 200 diamantes n\u00b03340 (c\u00f3digo DMC) Redondos o Cuadrados. \ud83c\udfa8 Color: Albaricoque \ud83c\udf08 Familia de colores: Marr\u00f3n anaranjado \u2b50 Calidad superior aprobada por nuestros clientes \u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3340\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\ud83d\udc8e Diamant Strass DMC - \ud83e\udd47 1er proveedor de cuentas diamond painting\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\ud83d\udc8e Diamantes DMC n\u00b03340 (Albaricoque) | Diamond Painting\" \/>\n\t\t<meta property=\"og:description\" content=\"Bolsa de 200 diamantes n\u00b03340 (c\u00f3digo DMC) Redondos o Cuadrados. \ud83c\udfa8 Color: Albaricoque \ud83c\udf08 Familia de colores: Marr\u00f3n anaranjado \u2b50 Calidad superior aprobada por nuestros clientes \u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3340\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-04-08T06:52:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-04-08T06:52:36+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\ud83d\udc8e Diamantes DMC n\u00b03340 (Albaricoque) | Diamond Painting\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Bolsa de 200 diamantes n\u00b03340 (c\u00f3digo DMC) Redondos o Cuadrados. \ud83c\udfa8 Color: Albaricoque \ud83c\udf08 Familia de colores: Marr\u00f3n anaranjado \u2b50 Calidad superior aprobada por nuestros clientes \u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3340\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/couleur\\\/naranja\\\/#listItem\",\"name\":\"\\ud83d\\udfe0 Naranja\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/couleur\\\/naranja\\\/#listItem\",\"position\":2,\"name\":\"\\ud83d\\udfe0 Naranja\",\"item\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/couleur\\\/naranja\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3340\\\/#listItem\",\"name\":\"Diamantes DMC n\\u00b03340 (Albaricoque)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#listItem\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3340\\\/#listItem\",\"position\":3,\"name\":\"Diamantes DMC n\\u00b03340 (Albaricoque)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/couleur\\\/naranja\\\/#listItem\",\"name\":\"\\ud83d\\udfe0 Naranja\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3340\\\/#itempage\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3340\\\/\",\"name\":\"\\ud83d\\udc8e Diamantes DMC n\\u00b03340 (Albaricoque) | Diamond Painting\",\"description\":\"Bolsa de 200 diamantes n\\u00b03340 (c\\u00f3digo DMC) Redondos o Cuadrados. \\ud83c\\udfa8 Color: Albaricoque \\ud83c\\udf08 Familia de colores: Marr\\u00f3n anaranjado \\u2b50 Calidad superior aprobada por nuestros clientes \\u2705 Tama\\u00f1o est\\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3340\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/wp-content\\\/uploads\\\/2022b\\\/02\\\/diamants-perles-dmc-3340.jpg\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3340\\\/#mainImage\",\"width\":2236,\"height\":1688},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3340\\\/#mainImage\"},\"datePublished\":\"2020-12-29T02:28:18+01:00\",\"dateModified\":\"2021-04-08T08:52:36+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#organization\",\"name\":\"Diamant Strass DMC\",\"description\":\"\\ud83e\\udd47 1er proveedor de cuentas diamond painting\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/\",\"telephone\":\"+33652550412\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cropped-Sans-titre-17.png\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3340\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3340\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/\",\"name\":\"\\ud83d\\udc8e Diamant Strass DMC\",\"description\":\"\\ud83e\\udd47 1er proveedor de cuentas diamond painting\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\ud83d\udc8e Diamantes DMC n\u00b03340 (Albaricoque) | Diamond Painting","description":"Bolsa de 200 diamantes n\u00b03340 (c\u00f3digo DMC) Redondos o Cuadrados. \ud83c\udfa8 Color: Albaricoque \ud83c\udf08 Familia de colores: Marr\u00f3n anaranjado \u2b50 Calidad superior aprobada por nuestros clientes \u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)","canonical_url":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3340\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3340\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/#listItem","position":1,"name":"Accueil","item":"https:\/\/diamant-strass-dmc.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/couleur\/naranja\/#listItem","name":"\ud83d\udfe0 Naranja"}},{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/couleur\/naranja\/#listItem","position":2,"name":"\ud83d\udfe0 Naranja","item":"https:\/\/diamant-strass-dmc.com\/es\/couleur\/naranja\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3340\/#listItem","name":"Diamantes DMC n\u00b03340 (Albaricoque)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/#listItem","name":"Accueil"}},{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3340\/#listItem","position":3,"name":"Diamantes DMC n\u00b03340 (Albaricoque)","previousItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/couleur\/naranja\/#listItem","name":"\ud83d\udfe0 Naranja"}}]},{"@type":"ItemPage","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3340\/#itempage","url":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3340\/","name":"\ud83d\udc8e Diamantes DMC n\u00b03340 (Albaricoque) | Diamond Painting","description":"Bolsa de 200 diamantes n\u00b03340 (c\u00f3digo DMC) Redondos o Cuadrados. \ud83c\udfa8 Color: Albaricoque \ud83c\udf08 Familia de colores: Marr\u00f3n anaranjado \u2b50 Calidad superior aprobada por nuestros clientes \u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3340\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2022b\/02\/diamants-perles-dmc-3340.jpg","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3340\/#mainImage","width":2236,"height":1688},"primaryImageOfPage":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3340\/#mainImage"},"datePublished":"2020-12-29T02:28:18+01:00","dateModified":"2021-04-08T08:52:36+02:00"},{"@type":"Organization","@id":"https:\/\/diamant-strass-dmc.com\/es\/#organization","name":"Diamant Strass DMC","description":"\ud83e\udd47 1er proveedor de cuentas diamond painting","url":"https:\/\/diamant-strass-dmc.com\/es\/","telephone":"+33652550412","logo":{"@type":"ImageObject","url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2022\/01\/cropped-Sans-titre-17.png","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3340\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3340\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/diamant-strass-dmc.com\/es\/#website","url":"https:\/\/diamant-strass-dmc.com\/es\/","name":"\ud83d\udc8e Diamant Strass DMC","description":"\ud83e\udd47 1er proveedor de cuentas diamond painting","inLanguage":"es-ES","publisher":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"\ud83d\udc8e Diamant Strass DMC - \ud83e\udd47 1er proveedor de cuentas diamond painting","og:type":"article","og:title":"\ud83d\udc8e Diamantes DMC n\u00b03340 (Albaricoque) | Diamond Painting","og:description":"Bolsa de 200 diamantes n\u00b03340 (c\u00f3digo DMC) Redondos o Cuadrados. \ud83c\udfa8 Color: Albaricoque \ud83c\udf08 Familia de colores: Marr\u00f3n anaranjado \u2b50 Calidad superior aprobada por nuestros clientes \u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)","og:url":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3340\/","og:image":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp","og:image:secure_url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp","article:published_time":"2021-04-08T06:52:36+00:00","article:modified_time":"2021-04-08T06:52:36+00:00","twitter:card":"summary","twitter:title":"\ud83d\udc8e Diamantes DMC n\u00b03340 (Albaricoque) | Diamond Painting","twitter:description":"Bolsa de 200 diamantes n\u00b03340 (c\u00f3digo DMC) Redondos o Cuadrados. \ud83c\udfa8 Color: Albaricoque \ud83c\udf08 Familia de colores: Marr\u00f3n anaranjado \u2b50 Calidad superior aprobada por nuestros clientes \u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)","twitter:image":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp"},"aioseo_meta_data":{"post_id":"20957","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":"none","schema_type_options":"{\"webPage\":{\"webPageType\":\"WebPage\"},\"article\":{\"articleType\":\"BlogPosting\"},\"book\":[],\"course\":[],\"event\":[],\"jobPosting\":[],\"music\":[],\"person\":[],\"product\":[],\"recipe\":[],\"restaurant\":[],\"service\":[],\"software\":[],\"video\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"businessInfo":{"name":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"line1":"","line2":"","zip":"","city":"","state":"","country":""},"contact":{"email":"","phone":"","fax":""},"ids":{"vatID":"","taxID":"","chamberID":""},"payment":{"priceIndication":"","currenciesAccepted":"","methodsAccepted":""},"areaServed":""},"openingHours":{"show":false,"closedLabel":"","open24h":false,"open24hLabel":"","open247":false,"use24hFormat":false,"twoSets":false,"timezone":"","hours":[]}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-04-08 06:52:37","updated":"2025-06-05 09:51:53","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product\/20957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product\/20957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/media\/90457"}],"wp:attachment":[{"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/media?parent=20957"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product_brand?post=20957"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product_cat?post=20957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}