{"id":20710,"date":"2020-12-29T02:28:18","date_gmt":"2021-04-08T06:50:29","guid":{"rendered":"https:\/\/diamant-strass-dmc.com\/perles-broderie\/diamantes-dmc-no-3053-tweed-verde\/"},"modified":"2021-04-08T08:50:29","modified_gmt":"2021-04-08T06:50:29","slug":"bolsa-diamantes-dmc-3053","status":"publish","type":"product","link":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3053\/","title":{"rendered":"Diamantes DMC n\u00b03053 (Tweed verde)"},"content":{"rendered":"<p>Bolsa de 200 <strong>diamantes n\u00b03053<\/strong> (c\u00f3digo DMC) <strong>redondos o cuadrados<\/strong>.<\/p>\n<p>\ud83c\udfa8 Colore: <strong>Tweed Green<\/strong><br \/>\ud83c\udf08 Familia de colores: <strong>Verde gris\u00e1ceo<\/strong><br \/>\u2b50 <strong>Calidad superior<\/strong> aprobada por nuestros clientes<br \/>\u2705 <strong>Tama\u00f1o est\u00e1ndar<\/strong> (cuadrados: 2,5 mm, redondos: 2,8 mm)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bolsa de 200 diamantes n\u00b03053 (c\u00f3digo DMC) redondos o cuadrados. \ud83c\udfa8 Colore: Tweed Green\ud83c\udf08 Familia de colores: Verde gris\u00e1ceo\u2b50 Calidad superior aprobada por nuestros clientes\u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)<\/p>\n","protected":false},"featured_media":92047,"template":"","meta":{"footnotes":""},"product_brand":[],"product_cat":[751],"class_list":["post-20710","product","type-product","status-publish","has-post-thumbnail","product_cat-verde-es","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Bolsa de 200 diamantes n\u00b03053 (c\u00f3digo DMC) redondos o cuadrados. \ud83c\udfa8 Colore: Tweed Green\ud83c\udf08 Familia de colores: Verde gris\u00e1ceo\u2b50 Calidad superior aprobada por nuestros clientes\u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3053\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\ud83d\udc8e Diamant Strass DMC - \ud83e\udd47 1er proveedor de cuentas diamond painting\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\ud83d\udc8e Diamantes DMC n\u00b03053 (Tweed verde) | Diamond Painting\" \/>\n\t\t<meta property=\"og:description\" content=\"Bolsa de 200 diamantes n\u00b03053 (c\u00f3digo DMC) redondos o cuadrados. \ud83c\udfa8 Colore: Tweed Green\ud83c\udf08 Familia de colores: Verde gris\u00e1ceo\u2b50 Calidad superior aprobada por nuestros clientes\u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3053\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-04-08T06:50:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-04-08T06:50:29+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\ud83d\udc8e Diamantes DMC n\u00b03053 (Tweed verde) | Diamond Painting\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Bolsa de 200 diamantes n\u00b03053 (c\u00f3digo DMC) redondos o cuadrados. \ud83c\udfa8 Colore: Tweed Green\ud83c\udf08 Familia de colores: Verde gris\u00e1ceo\u2b50 Calidad superior aprobada por nuestros clientes\u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3053\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/couleur\\\/verde-es\\\/#listItem\",\"name\":\"\\ud83d\\udfe2 Verde\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/couleur\\\/verde-es\\\/#listItem\",\"position\":2,\"name\":\"\\ud83d\\udfe2 Verde\",\"item\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/couleur\\\/verde-es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3053\\\/#listItem\",\"name\":\"Diamantes DMC n\\u00b03053 (Tweed verde)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#listItem\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3053\\\/#listItem\",\"position\":3,\"name\":\"Diamantes DMC n\\u00b03053 (Tweed verde)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/couleur\\\/verde-es\\\/#listItem\",\"name\":\"\\ud83d\\udfe2 Verde\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3053\\\/#itempage\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3053\\\/\",\"name\":\"\\ud83d\\udc8e Diamantes DMC n\\u00b03053 (Tweed verde) | Diamond Painting\",\"description\":\"Bolsa de 200 diamantes n\\u00b03053 (c\\u00f3digo DMC) redondos o cuadrados. \\ud83c\\udfa8 Colore: Tweed Green\\ud83c\\udf08 Familia de colores: Verde gris\\u00e1ceo\\u2b50 Calidad superior aprobada por nuestros clientes\\u2705 Tama\\u00f1o est\\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3053\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/wp-content\\\/uploads\\\/2022b\\\/02\\\/diamants-perles-dmc-3053.jpg\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3053\\\/#mainImage\",\"width\":2236,\"height\":1688},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3053\\\/#mainImage\"},\"datePublished\":\"2020-12-29T02:28:18+01:00\",\"dateModified\":\"2021-04-08T08:50:29+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#organization\",\"name\":\"Diamant Strass DMC\",\"description\":\"\\ud83e\\udd47 1er proveedor de cuentas diamond painting\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/\",\"telephone\":\"+33652550412\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cropped-Sans-titre-17.png\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3053\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-3053\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/\",\"name\":\"\\ud83d\\udc8e Diamant Strass DMC\",\"description\":\"\\ud83e\\udd47 1er proveedor de cuentas diamond painting\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\ud83d\udc8e Diamantes DMC n\u00b03053 (Tweed verde) | Diamond Painting","description":"Bolsa de 200 diamantes n\u00b03053 (c\u00f3digo DMC) redondos o cuadrados. \ud83c\udfa8 Colore: Tweed Green\ud83c\udf08 Familia de colores: Verde gris\u00e1ceo\u2b50 Calidad superior aprobada por nuestros clientes\u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)","canonical_url":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3053\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3053\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/#listItem","position":1,"name":"Accueil","item":"https:\/\/diamant-strass-dmc.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/couleur\/verde-es\/#listItem","name":"\ud83d\udfe2 Verde"}},{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/couleur\/verde-es\/#listItem","position":2,"name":"\ud83d\udfe2 Verde","item":"https:\/\/diamant-strass-dmc.com\/es\/couleur\/verde-es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3053\/#listItem","name":"Diamantes DMC n\u00b03053 (Tweed verde)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/#listItem","name":"Accueil"}},{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3053\/#listItem","position":3,"name":"Diamantes DMC n\u00b03053 (Tweed verde)","previousItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/couleur\/verde-es\/#listItem","name":"\ud83d\udfe2 Verde"}}]},{"@type":"ItemPage","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3053\/#itempage","url":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3053\/","name":"\ud83d\udc8e Diamantes DMC n\u00b03053 (Tweed verde) | Diamond Painting","description":"Bolsa de 200 diamantes n\u00b03053 (c\u00f3digo DMC) redondos o cuadrados. \ud83c\udfa8 Colore: Tweed Green\ud83c\udf08 Familia de colores: Verde gris\u00e1ceo\u2b50 Calidad superior aprobada por nuestros clientes\u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3053\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2022b\/02\/diamants-perles-dmc-3053.jpg","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3053\/#mainImage","width":2236,"height":1688},"primaryImageOfPage":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3053\/#mainImage"},"datePublished":"2020-12-29T02:28:18+01:00","dateModified":"2021-04-08T08:50:29+02:00"},{"@type":"Organization","@id":"https:\/\/diamant-strass-dmc.com\/es\/#organization","name":"Diamant Strass DMC","description":"\ud83e\udd47 1er proveedor de cuentas diamond painting","url":"https:\/\/diamant-strass-dmc.com\/es\/","telephone":"+33652550412","logo":{"@type":"ImageObject","url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2022\/01\/cropped-Sans-titre-17.png","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3053\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3053\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/diamant-strass-dmc.com\/es\/#website","url":"https:\/\/diamant-strass-dmc.com\/es\/","name":"\ud83d\udc8e Diamant Strass DMC","description":"\ud83e\udd47 1er proveedor de cuentas diamond painting","inLanguage":"es-ES","publisher":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"\ud83d\udc8e Diamant Strass DMC - \ud83e\udd47 1er proveedor de cuentas diamond painting","og:type":"article","og:title":"\ud83d\udc8e Diamantes DMC n\u00b03053 (Tweed verde) | Diamond Painting","og:description":"Bolsa de 200 diamantes n\u00b03053 (c\u00f3digo DMC) redondos o cuadrados. \ud83c\udfa8 Colore: Tweed Green\ud83c\udf08 Familia de colores: Verde gris\u00e1ceo\u2b50 Calidad superior aprobada por nuestros clientes\u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)","og:url":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-3053\/","og:image":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp","og:image:secure_url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp","article:published_time":"2021-04-08T06:50:29+00:00","article:modified_time":"2021-04-08T06:50:29+00:00","twitter:card":"summary","twitter:title":"\ud83d\udc8e Diamantes DMC n\u00b03053 (Tweed verde) | Diamond Painting","twitter:description":"Bolsa de 200 diamantes n\u00b03053 (c\u00f3digo DMC) redondos o cuadrados. \ud83c\udfa8 Colore: Tweed Green\ud83c\udf08 Familia de colores: Verde gris\u00e1ceo\u2b50 Calidad superior aprobada por nuestros clientes\u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)","twitter:image":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp"},"aioseo_meta_data":{"post_id":"20710","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-04-08 06:50:30","updated":"2025-06-05 09:43:37","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"_links":{"self":[{"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product\/20710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product\/20710\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/media\/92047"}],"wp:attachment":[{"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/media?parent=20710"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product_brand?post=20710"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product_cat?post=20710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}