{"id":11539,"date":"2020-12-29T02:27:46","date_gmt":"2021-04-08T06:08:22","guid":{"rendered":"https:\/\/diamant-strass-dmc.com\/perles-broderie\/diamantes-dmc-no-433-chocolate\/"},"modified":"2021-04-08T08:08:22","modified_gmt":"2021-04-08T06:08:22","slug":"bolsa-diamantes-dmc-433","status":"publish","type":"product","link":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-433\/","title":{"rendered":"Diamantes DMC n\u00b0433 (Chocolate)"},"content":{"rendered":"<p>Bolsa de 200 <strong>diamantes n\u00b0433<\/strong> (c\u00f3digo DMC) <strong>redondos o cuadrados<\/strong>.<\/p>\n<p>\ud83c\udfa8 Colore: <strong>Chocolate<\/strong><br \/>Familia de color: <strong>Marr\u00f3n<\/strong><br \/>\u2b50 <strong>Calidad superior<\/strong> aprobada por nuestros clientes<br \/>\u2705 <strong>Tama\u00f1o est\u00e1ndar<\/strong> (cuadrados: 2,5 mm, redondos: 2,8 mm)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bolsa de 200 diamantes n\u00b0433 (c\u00f3digo DMC) redondos o cuadrados. \ud83c\udfa8 Colore: ChocolateFamilia de color: Marr\u00f3n\u2b50 Calidad superior aprobada por nuestros clientes\u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)<\/p>\n","protected":false},"featured_media":95903,"template":"","meta":{"footnotes":""},"product_brand":[],"product_cat":[660],"class_list":["post-11539","product","type-product","status-publish","has-post-thumbnail","product_cat-castana","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Bolsa de 200 diamantes n\u00b0433 (c\u00f3digo DMC) redondos o cuadrados. \ud83c\udfa8 Colore: ChocolateFamilia de color: Marr\u00f3n\u2b50 Calidad superior aprobada por nuestros clientes\u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-433\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\ud83d\udc8e Diamant Strass DMC - \ud83e\udd47 1er proveedor de cuentas diamond painting\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\ud83d\udc8e Diamantes DMC n\u00b0433 (Chocolate) | Diamond Painting\" \/>\n\t\t<meta property=\"og:description\" content=\"Bolsa de 200 diamantes n\u00b0433 (c\u00f3digo DMC) redondos o cuadrados. \ud83c\udfa8 Colore: ChocolateFamilia de color: Marr\u00f3n\u2b50 Calidad superior aprobada por nuestros clientes\u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-433\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-04-08T06:08:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-04-08T06:08:22+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\ud83d\udc8e Diamantes DMC n\u00b0433 (Chocolate) | Diamond Painting\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Bolsa de 200 diamantes n\u00b0433 (c\u00f3digo DMC) redondos o cuadrados. \ud83c\udfa8 Colore: ChocolateFamilia de color: Marr\u00f3n\u2b50 Calidad superior aprobada por nuestros clientes\u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-433\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/couleur\\\/castana\\\/#listItem\",\"name\":\"\\ud83d\\udfe4 Marr\\u00f3n y beige\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/couleur\\\/castana\\\/#listItem\",\"position\":2,\"name\":\"\\ud83d\\udfe4 Marr\\u00f3n y beige\",\"item\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/couleur\\\/castana\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-433\\\/#listItem\",\"name\":\"Diamantes DMC n\\u00b0433 (Chocolate)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#listItem\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-433\\\/#listItem\",\"position\":3,\"name\":\"Diamantes DMC n\\u00b0433 (Chocolate)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/couleur\\\/castana\\\/#listItem\",\"name\":\"\\ud83d\\udfe4 Marr\\u00f3n y beige\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-433\\\/#itempage\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-433\\\/\",\"name\":\"\\ud83d\\udc8e Diamantes DMC n\\u00b0433 (Chocolate) | Diamond Painting\",\"description\":\"Bolsa de 200 diamantes n\\u00b0433 (c\\u00f3digo DMC) redondos o cuadrados. \\ud83c\\udfa8 Colore: ChocolateFamilia de color: Marr\\u00f3n\\u2b50 Calidad superior aprobada por nuestros clientes\\u2705 Tama\\u00f1o est\\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-433\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/wp-content\\\/uploads\\\/2022b\\\/02\\\/diamants-perles-dmc-433.jpg\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-433\\\/#mainImage\",\"width\":2236,\"height\":1688},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-433\\\/#mainImage\"},\"datePublished\":\"2020-12-29T02:27:46+01:00\",\"dateModified\":\"2021-04-08T08:08:22+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#organization\",\"name\":\"Diamant Strass DMC\",\"description\":\"\\ud83e\\udd47 1er proveedor de cuentas diamond painting\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/\",\"telephone\":\"+33652550412\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cropped-Sans-titre-17.png\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-433\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/perles-broderie\\\/bolsa-diamantes-dmc-433\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/\",\"name\":\"\\ud83d\\udc8e Diamant Strass DMC\",\"description\":\"\\ud83e\\udd47 1er proveedor de cuentas diamond painting\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\ud83d\udc8e Diamantes DMC n\u00b0433 (Chocolate) | Diamond Painting","description":"Bolsa de 200 diamantes n\u00b0433 (c\u00f3digo DMC) redondos o cuadrados. \ud83c\udfa8 Colore: ChocolateFamilia de color: Marr\u00f3n\u2b50 Calidad superior aprobada por nuestros clientes\u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)","canonical_url":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-433\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-433\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/#listItem","position":1,"name":"Accueil","item":"https:\/\/diamant-strass-dmc.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/couleur\/castana\/#listItem","name":"\ud83d\udfe4 Marr\u00f3n y beige"}},{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/couleur\/castana\/#listItem","position":2,"name":"\ud83d\udfe4 Marr\u00f3n y beige","item":"https:\/\/diamant-strass-dmc.com\/es\/couleur\/castana\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-433\/#listItem","name":"Diamantes DMC n\u00b0433 (Chocolate)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/#listItem","name":"Accueil"}},{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-433\/#listItem","position":3,"name":"Diamantes DMC n\u00b0433 (Chocolate)","previousItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/es\/couleur\/castana\/#listItem","name":"\ud83d\udfe4 Marr\u00f3n y beige"}}]},{"@type":"ItemPage","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-433\/#itempage","url":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-433\/","name":"\ud83d\udc8e Diamantes DMC n\u00b0433 (Chocolate) | Diamond Painting","description":"Bolsa de 200 diamantes n\u00b0433 (c\u00f3digo DMC) redondos o cuadrados. \ud83c\udfa8 Colore: ChocolateFamilia de color: Marr\u00f3n\u2b50 Calidad superior aprobada por nuestros clientes\u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-433\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2022b\/02\/diamants-perles-dmc-433.jpg","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-433\/#mainImage","width":2236,"height":1688},"primaryImageOfPage":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-433\/#mainImage"},"datePublished":"2020-12-29T02:27:46+01:00","dateModified":"2021-04-08T08:08:22+02:00"},{"@type":"Organization","@id":"https:\/\/diamant-strass-dmc.com\/es\/#organization","name":"Diamant Strass DMC","description":"\ud83e\udd47 1er proveedor de cuentas diamond painting","url":"https:\/\/diamant-strass-dmc.com\/es\/","telephone":"+33652550412","logo":{"@type":"ImageObject","url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2022\/01\/cropped-Sans-titre-17.png","@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-433\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-433\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/diamant-strass-dmc.com\/es\/#website","url":"https:\/\/diamant-strass-dmc.com\/es\/","name":"\ud83d\udc8e Diamant Strass DMC","description":"\ud83e\udd47 1er proveedor de cuentas diamond painting","inLanguage":"es-ES","publisher":{"@id":"https:\/\/diamant-strass-dmc.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"\ud83d\udc8e Diamant Strass DMC - \ud83e\udd47 1er proveedor de cuentas diamond painting","og:type":"article","og:title":"\ud83d\udc8e Diamantes DMC n\u00b0433 (Chocolate) | Diamond Painting","og:description":"Bolsa de 200 diamantes n\u00b0433 (c\u00f3digo DMC) redondos o cuadrados. \ud83c\udfa8 Colore: ChocolateFamilia de color: Marr\u00f3n\u2b50 Calidad superior aprobada por nuestros clientes\u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)","og:url":"https:\/\/diamant-strass-dmc.com\/es\/perles-broderie\/bolsa-diamantes-dmc-433\/","og:image":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp","og:image:secure_url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp","article:published_time":"2021-04-08T06:08:22+00:00","article:modified_time":"2021-04-08T06:08:22+00:00","twitter:card":"summary","twitter:title":"\ud83d\udc8e Diamantes DMC n\u00b0433 (Chocolate) | Diamond Painting","twitter:description":"Bolsa de 200 diamantes n\u00b0433 (c\u00f3digo DMC) redondos o cuadrados. \ud83c\udfa8 Colore: ChocolateFamilia de color: Marr\u00f3n\u2b50 Calidad superior aprobada por nuestros clientes\u2705 Tama\u00f1o est\u00e1ndar (cuadrados: 2,5 mm, redondos: 2,8 mm)","twitter:image":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp"},"aioseo_meta_data":{"post_id":"11539","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-04-08 06:08:23","updated":"2025-06-05 03:41:54","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product\/11539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product\/11539\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/media\/95903"}],"wp:attachment":[{"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/media?parent=11539"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product_brand?post=11539"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/es\/wp-json\/wp\/v2\/product_cat?post=11539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}