{"id":63642,"date":"2022-09-26T18:02:12","date_gmt":"2023-10-31T14:45:56","guid":{"rendered":"https:\/\/diamant-strass-dmc.com\/perles-broderie\/sachet-diamanten-ab-922\/"},"modified":"2023-10-31T15:45:58","modified_gmt":"2023-10-31T14:45:58","slug":"sachet-diamanten-ab-922","status":"publish","type":"product","link":"https:\/\/diamant-strass-dmc.com\/de\/perles-broderie\/sachet-diamanten-ab-922\/","title":{"rendered":"AB Steine 922 (Terracotta)"},"content":{"rendered":"<div class=\"abdiams\"><strong><span style=\"text-decoration: underline;\"><a href=\"\/de\/diamantmalerei-was-sind-ab-diamanten\/\">&#8220; Mehr \u00fcber AB Steine<\/a><\/span><\/strong><\/div>\n<p>Spezielle AB Steine (glitzernd, glitter\u00e4hnlicher Effekt).<\/p>\n<p><span style=\"color:blue;\">Quadratische Diamanten: 200 Perlen pro Beutel.<br \/>Runde Diamanten: 300 Perlen pro Beutel.<\/span><\/p>\n<p>Beutel mit Diamanten <strong>AB 922 <\/strong>(Code DMC), <strong>rund oder quadratisch<\/strong>, f\u00fcr die <strong>Diamantmalerei (Diamond Painting<\/strong> ).  <\/p>\n<p><strong>Standardgr\u00f6\u00dfe<\/strong>: Perlen, die zu allen Marken passen (quadratisch: 2,5 mm, rund: 2,8 mm).<\/p>\n<p>\ud83c\udfa8 Farbe: <strong>Terracotta<\/strong><br \/>\n\u2b50 Strasssteine aus Harz (h\u00f6here Qualit\u00e4t als Acryl).<\/p>\n<p>\u2705 Standardgr\u00f6\u00dfe <strong>kompatibel mit allen Leinw\u00e4nden<\/strong><br \/>\ud83d\ude9a <strong>Express-Lieferung<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220; Mehr \u00fcber AB Steine Spezielle AB Steine (glitzernd, glitter\u00e4hnlicher Effekt). Quadratische Diamanten: 200 Perlen pro Beutel.Runde Diamanten: 300 Perlen pro Beutel. Beutel mit Diamanten AB 922 (Code DMC), rund oder quadratisch, f\u00fcr die Diamantmalerei (Diamond Painting ). Standardgr\u00f6\u00dfe: Perlen, die zu allen Marken passen (quadratisch: 2,5 mm, rund: 2,8 mm). \ud83c\udfa8 Farbe: Terracotta \u2b50 [&hellip;]<\/p>\n","protected":false},"featured_media":90104,"template":"","meta":{"footnotes":""},"product_brand":[],"product_cat":[7244],"class_list":["post-63642","product","type-product","status-publish","has-post-thumbnail","product_cat-spezielle-steine-ab-und-crystal-ab","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-variable"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"&quot; Mehr \u00fcber AB Steine Spezielle AB Steine (glitzernd, glitter\u00e4hnlicher Effekt). Quadratische Diamanten: 200 Perlen pro Beutel.Runde Diamanten: 300 Perlen pro Beutel. Beutel mit Diamanten AB 922 (Code DMC), rund oder quadratisch, f\u00fcr die Diamantmalerei (Diamond Painting ). Standardgr\u00f6\u00dfe: Perlen, die zu allen Marken passen (quadratisch: 2,5 mm, rund: 2,8 mm). \ud83c\udfa8 Farbe: Terracotta \u2b50\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/diamant-strass-dmc.com\/de\/perles-broderie\/sachet-diamanten-ab-922\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\ud83d\udc8e Diamant Strass DMC - \ud83e\udd47 Erster Lieferant von Diamond Painting Perlen\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\ud83d\udc8e AB Steine 922 (Terracotta) | Strasssteine rund oder quadratisch\" \/>\n\t\t<meta property=\"og:description\" content=\"&quot; Mehr \u00fcber AB Steine Spezielle AB Steine (glitzernd, glitter\u00e4hnlicher Effekt). Quadratische Diamanten: 200 Perlen pro Beutel.Runde Diamanten: 300 Perlen pro Beutel. Beutel mit Diamanten AB 922 (Code DMC), rund oder quadratisch, f\u00fcr die Diamantmalerei (Diamond Painting ). Standardgr\u00f6\u00dfe: Perlen, die zu allen Marken passen (quadratisch: 2,5 mm, rund: 2,8 mm). \ud83c\udfa8 Farbe: Terracotta \u2b50\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/diamant-strass-dmc.com\/de\/perles-broderie\/sachet-diamanten-ab-922\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-10-31T14:45:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-10-31T14:45:58+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\ud83d\udc8e AB Steine 922 (Terracotta) | Strasssteine rund oder quadratisch\" \/>\n\t\t<meta name=\"twitter:description\" content=\"&quot; Mehr \u00fcber AB Steine Spezielle AB Steine (glitzernd, glitter\u00e4hnlicher Effekt). Quadratische Diamanten: 200 Perlen pro Beutel.Runde Diamanten: 300 Perlen pro Beutel. Beutel mit Diamanten AB 922 (Code DMC), rund oder quadratisch, f\u00fcr die Diamantmalerei (Diamond Painting ). Standardgr\u00f6\u00dfe: Perlen, die zu allen Marken passen (quadratisch: 2,5 mm, rund: 2,8 mm). \ud83c\udfa8 Farbe: Terracotta \u2b50\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/perles-broderie\\\/sachet-diamanten-ab-922\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/couleur\\\/spezielle-steine-ab-und-crystal-ab\\\/#listItem\",\"name\":\"Spezielle Steine AB (und Crystal AB)\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/couleur\\\/spezielle-steine-ab-und-crystal-ab\\\/#listItem\",\"position\":2,\"name\":\"Spezielle Steine AB (und Crystal AB)\",\"item\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/couleur\\\/spezielle-steine-ab-und-crystal-ab\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/perles-broderie\\\/sachet-diamanten-ab-922\\\/#listItem\",\"name\":\"AB Steine 922 (Terracotta)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/#listItem\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/perles-broderie\\\/sachet-diamanten-ab-922\\\/#listItem\",\"position\":3,\"name\":\"AB Steine 922 (Terracotta)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/couleur\\\/spezielle-steine-ab-und-crystal-ab\\\/#listItem\",\"name\":\"Spezielle Steine AB (und Crystal AB)\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/perles-broderie\\\/sachet-diamanten-ab-922\\\/#itempage\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/perles-broderie\\\/sachet-diamanten-ab-922\\\/\",\"name\":\"\\ud83d\\udc8e AB Steine 922 (Terracotta) | Strasssteine rund oder quadratisch\",\"description\":\"\\\" Mehr \\u00fcber AB Steine Spezielle AB Steine (glitzernd, glitter\\u00e4hnlicher Effekt). Quadratische Diamanten: 200 Perlen pro Beutel.Runde Diamanten: 300 Perlen pro Beutel. Beutel mit Diamanten AB 922 (Code DMC), rund oder quadratisch, f\\u00fcr die Diamantmalerei (Diamond Painting ). Standardgr\\u00f6\\u00dfe: Perlen, die zu allen Marken passen (quadratisch: 2,5 mm, rund: 2,8 mm). \\ud83c\\udfa8 Farbe: Terracotta \\u2b50\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/perles-broderie\\\/sachet-diamanten-ab-922\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/wp-content\\\/uploads\\\/2022b\\\/02\\\/diamants-perles-dmc-922.jpg\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/perles-broderie\\\/sachet-diamanten-ab-922\\\/#mainImage\",\"width\":2236,\"height\":1688},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/perles-broderie\\\/sachet-diamanten-ab-922\\\/#mainImage\"},\"datePublished\":\"2022-09-26T18:02:12+02:00\",\"dateModified\":\"2023-10-31T15:45:58+01:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/#organization\",\"name\":\"Diamant Strass DMC\",\"description\":\"\\ud83e\\udd47 Erster Lieferant von Diamond Painting Perlen\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/\",\"telephone\":\"+33652550412\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cropped-Sans-titre-17.png\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/perles-broderie\\\/sachet-diamanten-ab-922\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/perles-broderie\\\/sachet-diamanten-ab-922\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/\",\"name\":\"\\ud83d\\udc8e Diamant Strass DMC\",\"description\":\"\\ud83e\\udd47 Erster Lieferant von Diamond Painting Perlen\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/diamant-strass-dmc.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\ud83d\udc8e AB Steine 922 (Terracotta) | Strasssteine rund oder quadratisch","description":"\" Mehr \u00fcber AB Steine Spezielle AB Steine (glitzernd, glitter\u00e4hnlicher Effekt). Quadratische Diamanten: 200 Perlen pro Beutel.Runde Diamanten: 300 Perlen pro Beutel. Beutel mit Diamanten AB 922 (Code DMC), rund oder quadratisch, f\u00fcr die Diamantmalerei (Diamond Painting ). Standardgr\u00f6\u00dfe: Perlen, die zu allen Marken passen (quadratisch: 2,5 mm, rund: 2,8 mm). \ud83c\udfa8 Farbe: Terracotta \u2b50","canonical_url":"https:\/\/diamant-strass-dmc.com\/de\/perles-broderie\/sachet-diamanten-ab-922\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/diamant-strass-dmc.com\/de\/perles-broderie\/sachet-diamanten-ab-922\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/de\/#listItem","position":1,"name":"Accueil","item":"https:\/\/diamant-strass-dmc.com\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/de\/couleur\/spezielle-steine-ab-und-crystal-ab\/#listItem","name":"Spezielle Steine AB (und Crystal AB)"}},{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/de\/couleur\/spezielle-steine-ab-und-crystal-ab\/#listItem","position":2,"name":"Spezielle Steine AB (und Crystal AB)","item":"https:\/\/diamant-strass-dmc.com\/de\/couleur\/spezielle-steine-ab-und-crystal-ab\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/de\/perles-broderie\/sachet-diamanten-ab-922\/#listItem","name":"AB Steine 922 (Terracotta)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/de\/#listItem","name":"Accueil"}},{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/de\/perles-broderie\/sachet-diamanten-ab-922\/#listItem","position":3,"name":"AB Steine 922 (Terracotta)","previousItem":{"@type":"ListItem","@id":"https:\/\/diamant-strass-dmc.com\/de\/couleur\/spezielle-steine-ab-und-crystal-ab\/#listItem","name":"Spezielle Steine AB (und Crystal AB)"}}]},{"@type":"ItemPage","@id":"https:\/\/diamant-strass-dmc.com\/de\/perles-broderie\/sachet-diamanten-ab-922\/#itempage","url":"https:\/\/diamant-strass-dmc.com\/de\/perles-broderie\/sachet-diamanten-ab-922\/","name":"\ud83d\udc8e AB Steine 922 (Terracotta) | Strasssteine rund oder quadratisch","description":"\" Mehr \u00fcber AB Steine Spezielle AB Steine (glitzernd, glitter\u00e4hnlicher Effekt). Quadratische Diamanten: 200 Perlen pro Beutel.Runde Diamanten: 300 Perlen pro Beutel. Beutel mit Diamanten AB 922 (Code DMC), rund oder quadratisch, f\u00fcr die Diamantmalerei (Diamond Painting ). Standardgr\u00f6\u00dfe: Perlen, die zu allen Marken passen (quadratisch: 2,5 mm, rund: 2,8 mm). \ud83c\udfa8 Farbe: Terracotta \u2b50","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/diamant-strass-dmc.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/diamant-strass-dmc.com\/de\/perles-broderie\/sachet-diamanten-ab-922\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2022b\/02\/diamants-perles-dmc-922.jpg","@id":"https:\/\/diamant-strass-dmc.com\/de\/perles-broderie\/sachet-diamanten-ab-922\/#mainImage","width":2236,"height":1688},"primaryImageOfPage":{"@id":"https:\/\/diamant-strass-dmc.com\/de\/perles-broderie\/sachet-diamanten-ab-922\/#mainImage"},"datePublished":"2022-09-26T18:02:12+02:00","dateModified":"2023-10-31T15:45:58+01:00"},{"@type":"Organization","@id":"https:\/\/diamant-strass-dmc.com\/de\/#organization","name":"Diamant Strass DMC","description":"\ud83e\udd47 Erster Lieferant von Diamond Painting Perlen","url":"https:\/\/diamant-strass-dmc.com\/de\/","telephone":"+33652550412","logo":{"@type":"ImageObject","url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2022\/01\/cropped-Sans-titre-17.png","@id":"https:\/\/diamant-strass-dmc.com\/de\/perles-broderie\/sachet-diamanten-ab-922\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/diamant-strass-dmc.com\/de\/perles-broderie\/sachet-diamanten-ab-922\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/diamant-strass-dmc.com\/de\/#website","url":"https:\/\/diamant-strass-dmc.com\/de\/","name":"\ud83d\udc8e Diamant Strass DMC","description":"\ud83e\udd47 Erster Lieferant von Diamond Painting Perlen","inLanguage":"de-DE","publisher":{"@id":"https:\/\/diamant-strass-dmc.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"\ud83d\udc8e Diamant Strass DMC - \ud83e\udd47 Erster Lieferant von Diamond Painting Perlen","og:type":"article","og:title":"\ud83d\udc8e AB Steine 922 (Terracotta) | Strasssteine rund oder quadratisch","og:description":"&quot; Mehr \u00fcber AB Steine Spezielle AB Steine (glitzernd, glitter\u00e4hnlicher Effekt). Quadratische Diamanten: 200 Perlen pro Beutel.Runde Diamanten: 300 Perlen pro Beutel. Beutel mit Diamanten AB 922 (Code DMC), rund oder quadratisch, f\u00fcr die Diamantmalerei (Diamond Painting ). Standardgr\u00f6\u00dfe: Perlen, die zu allen Marken passen (quadratisch: 2,5 mm, rund: 2,8 mm). \ud83c\udfa8 Farbe: Terracotta \u2b50","og:url":"https:\/\/diamant-strass-dmc.com\/de\/perles-broderie\/sachet-diamanten-ab-922\/","og:image":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp","og:image:secure_url":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp","article:published_time":"2023-10-31T14:45:56+00:00","article:modified_time":"2023-10-31T14:45:58+00:00","twitter:card":"summary","twitter:title":"\ud83d\udc8e AB Steine 922 (Terracotta) | Strasssteine rund oder quadratisch","twitter:description":"&quot; Mehr \u00fcber AB Steine Spezielle AB Steine (glitzernd, glitter\u00e4hnlicher Effekt). Quadratische Diamanten: 200 Perlen pro Beutel.Runde Diamanten: 300 Perlen pro Beutel. Beutel mit Diamanten AB 922 (Code DMC), rund oder quadratisch, f\u00fcr die Diamantmalerei (Diamond Painting ). Standardgr\u00f6\u00dfe: Perlen, die zu allen Marken passen (quadratisch: 2,5 mm, rund: 2,8 mm). \ud83c\udfa8 Farbe: Terracotta \u2b50","twitter:image":"https:\/\/diamant-strass-dmc.com\/wp-content\/uploads\/2026\/06\/logov2-diamantstrassdmc-120.webp"},"aioseo_meta_data":{"post_id":"63642","title":"\ud83d\udc8e #post_title | Strasssteine rund oder quadratisch","description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"},\"blockGraphs\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-10-31 14:45:57","updated":"2023-10-31 14:45:59","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/diamant-strass-dmc.com\/de\/wp-json\/wp\/v2\/product\/63642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diamant-strass-dmc.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/diamant-strass-dmc.com\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/diamant-strass-dmc.com\/de\/wp-json\/wp\/v2\/product\/63642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/de\/wp-json\/wp\/v2\/media\/90104"}],"wp:attachment":[{"href":"https:\/\/diamant-strass-dmc.com\/de\/wp-json\/wp\/v2\/media?parent=63642"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/de\/wp-json\/wp\/v2\/product_brand?post=63642"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/diamant-strass-dmc.com\/de\/wp-json\/wp\/v2\/product_cat?post=63642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}